{"id":23797,"date":"2025-04-16T11:42:11","date_gmt":"2025-04-16T11:42:11","guid":{"rendered":"https:\/\/malvern.onyx-sites.io\/?page_id=23797"},"modified":"2026-07-02T15:00:49","modified_gmt":"2026-07-02T15:00:49","slug":"dichiarazione-di-salute-e-sicurezza","status":"publish","type":"page","link":"https:\/\/malvernhouse.com\/it\/useful-information\/policies\/health-and-safety-statement\/","title":{"rendered":"Dichiarazione di salute e sicurezza"},"content":{"rendered":"<div data-elementor-type=\"wp-page\" data-elementor-id=\"23797\" class=\"elementor elementor-23797\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-6cb3ce69 body-header-small colour-block e-flex e-con-boxed translate-yes e-con e-parent\" data-id=\"6cb3ce69\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-77929e24 section-style-blue elementor-widget elementor-widget-Section settings\" data-id=\"77929e24\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"Section settings.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-57e0210a e-con-full e-flex translate-yes e-con e-child\" data-id=\"57e0210a\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-67c4cc7d elementor-widget elementor-widget-heading\" data-id=\"67c4cc7d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<span class=\"elementor-heading-title elementor-size-default\">Politiche di Malvern<\/span>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-714138e9 e-con-full e-flex translate-yes e-con e-child\" data-id=\"714138e9\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-e59987b elementor-widget elementor-widget-heading\" data-id=\"e59987b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Dichiarazione di salute e sicurezza<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-c4ada63 e-grid e-con-boxed translate-yes e-con e-parent\" data-id=\"c4ada63\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1cfae74 elementor-widget elementor-widget-text-editor\" data-id=\"1cfae74\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"wpb_text_column wpb_content_element\"><div class=\"wpb_wrapper\"><p><span data-contrast=\"auto\">Quanto segue \u00e8 una dichiarazione della politica di salute e sicurezza di Malvern International PLC in conformit\u00e0 con la Sezione 2 dell'Health and Safety at Work etc. Act 1974.<\/span><span data-ccp-props=\"{}\">\u00a0<\/span><\/p><p><span data-contrast=\"auto\">\u00c8 politica di Malvern International PLC garantire, nella misura ragionevolmente praticabile, la salute, la sicurezza e il benessere di tutti i dipendenti, studenti, appaltatori e visitatori, e di chiunque altro possa essere interessato dalle nostre attivit\u00e0.<\/span><span data-ccp-props=\"{}\">\u00a0<\/span><\/p><p><span data-contrast=\"auto\">Malvern International riconosce che la chiave per una gestione efficace della salute e sicurezza richiede una politica, un'organizzazione e disposizioni efficaci che riflettano l'impegno del management dell'organizzazione. Per mantenere tale impegno, misuriamo, monitoriamo, miglioriamo e rivediamo continuamente le nostre disposizioni in materia di salute e sicurezza per garantire che gli standard siano adeguatamente mantenuti in tutti i nostri siti e attivit\u00e0.<\/span><span data-ccp-props=\"{}\">\u00a0<\/span><\/p><h2>Responsabilit\u00e0<\/h2><p><span data-contrast=\"auto\">Il Consiglio di Malvern International PLC mantiene la responsabilit\u00e0 ultima per le prestazioni in materia di salute e sicurezza in tutto il Gruppo. La responsabilit\u00e0 operativa per l'attuazione e la supervisione di questa politica spetta al Chief Operating Officer, supportato dal Coordinatore del Gruppo per la Salute e Sicurezza e dai team di leadership delle filiali in tutto il Gruppo.<\/span><span data-ccp-props=\"{}\">\u00a0<\/span><\/p><p><span data-contrast=\"auto\">Malvern International riconosce che una gestione efficace della salute e della sicurezza contribuisce a un successo aziendale e didattico e stanzier\u00e0 finanziamenti e risorse adeguate per soddisfare tali esigenze.<\/span><span data-ccp-props=\"{}\">\u00a0<\/span><\/p><p><span data-contrast=\"auto\">La promozione della salute e della sicurezza \u00e8 di fondamentale importanza per noi, ed \u00e8 nostra politica fare tutto ci\u00f2 che \u00e8 ragionevolmente possibile per prevenire infortuni personali e danni a propriet\u00e0. L'organizzazione mira a proteggere tutti, inclusi studenti, visitatori e membri del pubblico, nella misura in cui entrano in contatto con le nostre attivit\u00e0, da qualsiasi pericolo o rischio prevedibile.<\/span><span data-ccp-props=\"{}\">\u00a0<\/span><\/p><p><span data-contrast=\"auto\">Tutti i dipendenti hanno doveri ai sensi dell'Health and Safety at Work etc. Act 1974 e sono informati della loro responsabilit\u00e0 personale di adottare ragionevoli precauzioni per la propria salute e sicurezza e per quella di altri che potrebbero essere interessati dai loro atti o omissioni. Ai dipendenti \u00e8 inoltre richiesto di collaborare con l'organizzazione in modo che possa conformarsi ai requisiti legali imposti su di essa e all'attuazione della presente politica. Studenti, visitatori e appaltatori sono ugualmente tenuti ad adottare ragionevoli precauzioni per la propria sicurezza e a seguire le istruzioni e le procedure di salute e sicurezza vigenti nei nostri siti.<\/span><\/p><h2>Comunicazione<\/h2><p><span data-contrast=\"auto\">Malvern International garantir\u00e0 una consultazione continua con i dipendenti per consentire la discussione di punti di vista e raccomandazioni a intervalli regolari, anche attraverso la nostra struttura del Comitato per la salute e la sicurezza, le bacheche e le discussioni informali.<\/span><span data-ccp-props=\"{}\">\u00a0<\/span><\/p><p><span data-contrast=\"auto\">Malvern International garantir\u00e0 un approccio sistematico per l'identificazione dei pericoli, la valutazione dei rischi, la definizione di misure di controllo adeguate e sufficienti e l'informazione di dipendenti, studenti e altri sulle procedure necessarie per mantenere un ambiente sicuro. Forniremo, per quanto ragionevolmente praticabile, locali e sistemi di lavoro sicuri, attrezzature sicure, manipolazione sicura di materiali e sostanze, fornitura di attrezzature di sicurezza adeguate e informazioni, istruzioni, formazione e supervisione appropriate.<\/span><span data-ccp-props=\"{}\">\u00a0<\/span><\/p><p><span data-contrast=\"auto\">Questa dichiarazione viene rivista annualmente ed \u00e8 supportata dalla nostra completa Politica di Gruppo sulla Salute e Sicurezza, che ne espone in dettaglio i nostri accordi.<\/span><span data-ccp-props=\"{}\">\u00a0<\/span><\/p><\/div><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Malvern Policies Health and safety statement The following is a statement of Malvern International PLC&#8217;s health and safety policy\u00a0in accordance with\u00a0Section 2 of the Health and Safety at Work etc. Act 1974.\u00a0 It is the policy of Malvern International PLC to ensure,\u00a0so far as\u00a0is reasonably\u00a0practicable, the health, safety and welfare of all employees, students,\u00a0contractors\u00a0and visitors, [&hellip;]<\/p>\n","protected":false},"author":27,"featured_media":0,"parent":23587,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-23797","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Health and safety statement | Malvern House<\/title>\n<meta name=\"description\" content=\"Malvern House prioritises the health and safety of all students, staff, and visitors.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/malvernhouse.com\/it\/informazioni-utili\/politiche\/dichiarazione-di-salute-e-sicurezza\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Health and safety statement | Malvern House\" \/>\n<meta property=\"og:description\" content=\"Malvern House prioritises the health and safety of all students, staff, and visitors.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/malvernhouse.com\/it\/informazioni-utili\/politiche\/dichiarazione-di-salute-e-sicurezza\/\" \/>\n<meta property=\"og:site_name\" content=\"Malvern House\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-02T15:00:49+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/8d4250430138cef3ae46.b-cdn.net\/wp-content\/uploads\/2025\/05\/MH_SocialsFallback-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"675\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/malvernhouse.com\\\/useful-information\\\/policies\\\/health-and-safety-statement\\\/\",\"url\":\"https:\\\/\\\/malvernhouse.com\\\/useful-information\\\/policies\\\/health-and-safety-statement\\\/\",\"name\":\"Health and safety statement | Malvern House\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/malvernhouse.com\\\/#website\"},\"datePublished\":\"2025-04-16T11:42:11+00:00\",\"dateModified\":\"2026-07-02T15:00:49+00:00\",\"description\":\"Malvern House prioritises the health and safety of all students, staff, and visitors.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/malvernhouse.com\\\/useful-information\\\/policies\\\/health-and-safety-statement\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/malvernhouse.com\\\/useful-information\\\/policies\\\/health-and-safety-statement\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/malvernhouse.com\\\/useful-information\\\/policies\\\/health-and-safety-statement\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/malvernhouse.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Useful information\",\"item\":\"https:\\\/\\\/malvernhouse.com\\\/useful-information\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Policies\",\"item\":\"https:\\\/\\\/malvernhouse.com\\\/useful-information\\\/policies\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Health and safety statement\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/malvernhouse.com\\\/#website\",\"url\":\"https:\\\/\\\/malvernhouse.com\\\/\",\"name\":\"Malvern House\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/malvernhouse.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Dichiarazione di salute e sicurezza | Malvern House","description":"La Malvern House d\u00e0 priorit\u00e0 alla salute e alla sicurezza di tutti gli studenti, del personale e dei visitatori.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/malvernhouse.com\/it\/informazioni-utili\/politiche\/dichiarazione-di-salute-e-sicurezza\/","og_locale":"it_IT","og_type":"article","og_title":"Health and safety statement | Malvern House","og_description":"Malvern House prioritises the health and safety of all students, staff, and visitors.","og_url":"https:\/\/malvernhouse.com\/it\/informazioni-utili\/politiche\/dichiarazione-di-salute-e-sicurezza\/","og_site_name":"Malvern House","article_modified_time":"2026-07-02T15:00:49+00:00","og_image":[{"width":1200,"height":675,"url":"https:\/\/8d4250430138cef3ae46.b-cdn.net\/wp-content\/uploads\/2025\/05\/MH_SocialsFallback-1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/malvernhouse.com\/useful-information\/policies\/health-and-safety-statement\/","url":"https:\/\/malvernhouse.com\/useful-information\/policies\/health-and-safety-statement\/","name":"Dichiarazione di salute e sicurezza | Malvern House","isPartOf":{"@id":"https:\/\/malvernhouse.com\/#website"},"datePublished":"2025-04-16T11:42:11+00:00","dateModified":"2026-07-02T15:00:49+00:00","description":"La Malvern House d\u00e0 priorit\u00e0 alla salute e alla sicurezza di tutti gli studenti, del personale e dei visitatori.","breadcrumb":{"@id":"https:\/\/malvernhouse.com\/useful-information\/policies\/health-and-safety-statement\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/malvernhouse.com\/useful-information\/policies\/health-and-safety-statement\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/malvernhouse.com\/useful-information\/policies\/health-and-safety-statement\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/malvernhouse.com\/"},{"@type":"ListItem","position":2,"name":"Useful information","item":"https:\/\/malvernhouse.com\/useful-information\/"},{"@type":"ListItem","position":3,"name":"Policies","item":"https:\/\/malvernhouse.com\/useful-information\/policies\/"},{"@type":"ListItem","position":4,"name":"Health and safety statement"}]},{"@type":"WebSite","@id":"https:\/\/malvernhouse.com\/#website","url":"https:\/\/malvernhouse.com\/","name":"Casa Malvern","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/malvernhouse.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"}]}},"_links":{"self":[{"href":"https:\/\/malvernhouse.com\/it\/wp-json\/wp\/v2\/pages\/23797","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/malvernhouse.com\/it\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/malvernhouse.com\/it\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/malvernhouse.com\/it\/wp-json\/wp\/v2\/users\/27"}],"replies":[{"embeddable":true,"href":"https:\/\/malvernhouse.com\/it\/wp-json\/wp\/v2\/comments?post=23797"}],"version-history":[{"count":18,"href":"https:\/\/malvernhouse.com\/it\/wp-json\/wp\/v2\/pages\/23797\/revisions"}],"predecessor-version":[{"id":45691,"href":"https:\/\/malvernhouse.com\/it\/wp-json\/wp\/v2\/pages\/23797\/revisions\/45691"}],"up":[{"embeddable":true,"href":"https:\/\/malvernhouse.com\/it\/wp-json\/wp\/v2\/pages\/23587"}],"wp:attachment":[{"href":"https:\/\/malvernhouse.com\/it\/wp-json\/wp\/v2\/media?parent=23797"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}